{"id":44,"date":"2025-10-22T17:04:16","date_gmt":"2025-10-22T15:04:16","guid":{"rendered":"https:\/\/si.zinnejstrony.pl\/?page_id=44"},"modified":"2025-11-14T18:16:16","modified_gmt":"2025-11-14T17:16:16","slug":"faq","status":"publish","type":"page","link":"https:\/\/sinfinityclothing.com\/en\/faq\/","title":{"rendered":"FAQ"},"content":{"rendered":"<section class=\"wp-block-greenshift-blocks-row alignfull gspb_row gspb_row-id-gsbp-86f7b08 your-parallax-section\" id=\"gspb_row-id-gsbp-86f7b08\"><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--12 gspb_col-id-gsbp-96a103f\" id=\"gspb_col-id-gsbp-96a103f\">\n<div class=\"wp-block-greenshift-blocks-container gspb_container gspb_container-gsbp-51c4d8a\" id=\"gspb_container-id-gsbp-51c4d8a\"><div class=\"gspb_backgroundOverlay\"><\/div>\n<div class=\"wp-block-greenshift-blocks-iconbox gspb_iconBox gspb_iconBox-id-gsbp-8d3d130\" id=\"gspb_iconBox-id-gsbp-8d3d130\"><div class=\"gspb_iconBox__wrapper\" style=\"display:inline-flex\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"72\" height=\"72\" viewbox=\"0 0 896 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M647.12 102.4c-41.6 38.6-79.16 79.18-112.44 119.94-54.52-75.1-122.12-151.28-198.68-222.34-196.52 182.34-336 419.92-336 563.2 0 254.5 200.58 460.8 448 460.8s448-206.3 448-460.8c0-106.54-103.96-326.28-248.88-460.8zM608.18 783.7c-43.32 30.32-96.74 48.3-154.46 48.3-144.3 0-261.72-95.48-261.72-250.5 0-77.22 48.62-145.26 145.58-261.5 13.86 15.96 197.66 250.68 197.66 250.68l117.26-133.76c8.28 13.7 15.82 27.1 22.54 39.94 54.7 104.38 31.62 237.94-66.86 306.84z\"><\/path><\/svg><\/div><\/div>\n\n\n\n<div id=\"gspb_text-id-gsbp-5360b17\" class=\"gspb_text gspb_text-id-gsbp-5360b17\">Najcz\u0119\u015bciej zadawane pytania<\/div>\n<\/div>\n\n\n\n<script>\n\/\/ Add this via Greenshift's custom JS or a site JS snippet plugin\ndocument.addEventListener('scroll', () => {\n  document.querySelectorAll('.your-parallax-section').forEach((el) => {\n    const speed = 0.4; \/\/ adjust speed (0.2 = slow, 0.6 = faster)\n    const yOffset = window.scrollY * speed;\n    el.style.backgroundPosition = `center calc(50% + ${yOffset}px)`;\n  });\n});\n\n<\/script>\n\n\n\n<h2 id=\"gspb_heading-id-gsbp-22ade7e\" class=\"gspb_heading gspb_heading-id-gsbp-22ade7e\">FAQ<\/h2>\n\n\n\n<p class=\"has-text-align-center has-text-color has-link-color wp-elements-8934bfc309d9f2c8371f301112d63eed wp-block-paragraph\" style=\"color:#bbbbbb\">Drukujemy dla zespo\u0142\u00f3w, marek i event\u00f3w w ca\u0142ej Polsce. W naszych realizacjach zobaczysz, jak \u0142\u0105czymy kreatywne pomys\u0142y z precyzyjn\u0105 produkcj\u0105 \u2014 od merchu i odzie\u017cy po scenografi\u0119 i materia\u0142y eventowe.<\/p>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n <\/div><\/section>\n\n\n\n<section class=\"wp-block-greenshift-blocks-row alignfull gspb_row gspb_row-id-gsbp-fc3aee0\" id=\"gspb_row-id-gsbp-fc3aee0\"><div class=\"gspb_row__content\"> \n<div class=\"wp-block-greenshift-blocks-row-column gspb_row__col--12 gspb_col-id-gsbp-573af12\" id=\"gspb_col-id-gsbp-573af12\">\n<div class=\"wp-block-greenshift-blocks-accordion gs-accordion gspb_accordion-id-gsbp-eaac55e togglelogic\" id=\"gspb_accordion-id-gsbp-eaac55e\" data-scroll=\"true\" itemscope itemtype=\"https:\/\/schema.org\/FAQPage\">\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-ba9b996 gsopen\" id=\"gspb_accordionitem-gsbp-ba9b996\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-0\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-ba9b996\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 704 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M352 160c-105.88 0-192 86.12-192 192 0 17.68 14.32 32 32 32s32-14.32 32-32c0-70.6 57.44-128 128-128 17.68 0 32-14.32 32-32s-14.32-32-32-32zM192.12 918.34c0 6.3 1.86 12.44 5.36 17.68l49.020 73.68c5.94 8.92 15.94 14.28 26.64 14.28h157.7c10.72 0 20.72-5.36 26.64-14.28l49.020-73.68c3.48-5.24 5.34-11.4 5.36-17.68l0.1-86.36h-319.92l0.080 86.36zM352 0c-204.56 0-352 165.94-352 352 0 88.74 32.9 169.7 87.12 231.56 33.28 37.98 85.48 117.6 104.84 184.32v0.12h96v-0.24c-0.020-9.54-1.44-19.020-4.3-28.14-11.18-35.62-45.64-129.54-124.34-219.34-41.080-46.86-63.040-106.3-63.22-168.28-0.4-147.28 119.34-256 255.9-256 141.16 0 256 114.84 256 256 0 61.94-22.48 121.7-63.3 168.28-78.22 89.22-112.84 182.94-124.2 218.92-2.805 8.545-4.428 18.381-4.44 28.594l-0 0.006v0.2h96v-0.1c19.36-66.74 71.56-146.36 104.84-184.32 54.2-61.88 87.1-142.84 87.1-231.58 0-194.4-157.6-352-352-352z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">Kilka podstawowych informacji na linii Sinfinity Clothing &#8211; Klient \u2014 WYCENA, PLIKI<\/div><meta itemprop=\"name\" content=\"Kilka podstawowych informacji na linii Sinfinity Clothing - Klient \u2014 WYCENA, PLIKI\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-0\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-ba9b996\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">Do wyceny zawsze potrzebujemy pliku graficznego, najlepiej w postaci gotowego mockupa + plik produkcyjny (w przypadku grafiki rastrowej).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pliki wektorowe przyjmujemy w formatach: pdf, ai, eps, cdr, svg<br>Pliki rastrowe: rozmiar 1:1, 300 dpi, pdf, tif, eps, png<br>Max rozmiar druku: 31x46cm<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-be6771d gsopen\" id=\"gspb_accordionitem-gsbp-be6771d\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-1\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-be6771d\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 1024 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M512 16c-273.914 0-496 222.166-496 496 0 273.994 222.086 496 496 496s496-222.006 496-496c0-273.834-222.086-496-496-496zM512 912c-221.064 0-400-178.862-400-400 0-220.99 178.944-400 400-400 220.982 0 400 178.942 400 400 0 221.060-178.862 400-400 400zM726.488 401.6c0 134.104-144.842 136.168-144.842 185.726v12.674c0 13.254-10.746 24-24 24h-91.294c-13.254 0-24-10.746-24-24v-17.318c0-71.49 54.2-100.068 95.158-123.032 35.122-19.69 56.648-33.082 56.648-59.158 0-34.492-43.998-57.386-79.568-57.386-46.378 0-67.788 21.954-97.884 59.938-8.114 10.24-22.92 12.142-33.332 4.248l-55.648-42.196c-10.214-7.744-12.502-22.132-5.288-32.726 47.254-69.388 107.442-108.37 201.15-108.37 98.142 0 202.9 76.608 202.9 177.6zM596 736c0 46.318-37.682 84-84 84s-84-37.682-84-84 37.682-84 84-84 84 37.682 84 84z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">WIZUALE \/ MOCKUPY<\/div><meta itemprop=\"name\" content=\"WIZUALE \/ MOCKUPY\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-1\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-be6771d\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">Wizualizacja jest pogl\u0105dowa. Akceptacja wizualizacji projektu jest wi\u0105\u017c\u0105ca, ale nale\u017cy pami\u0119ta\u0107, \u017ce sitodruk rz\u0105dzi si\u0119 swoimi prawami. Im bardziej skomplikowany wz\u00f3r, tym wi\u0119ksze pole do rozbie\u017cno\u015bci mi\u0119dzy wizualizacj\u0105 a efektem finalnym. Prosz\u0119 wzi\u0105\u0107 pod uwag\u0119, \u017ce sitodruk nie jest technologi\u0105 druku cyfrowego \u2013 nigdy nie b\u0119dzie w 100% wygl\u0105da\u0142 jak grafika na ekranie komputera. Umiejscowienie i rozmiar wzoru na mockupie tak\u017ce s\u0105 pogl\u0105dowe.<br>Rozmiar nadruku jest jeden i dopasowujemy go do danego rozmiaru drukowanej koszulki.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-00e70a1 gsopen\" id=\"gspb_accordionitem-gsbp-00e70a1\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-2\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-00e70a1\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 1024 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M512 16c-273.914 0-496 222.166-496 496 0 273.994 222.086 496 496 496s496-222.006 496-496c0-273.834-222.086-496-496-496zM512 912c-221.064 0-400-178.862-400-400 0-220.99 178.944-400 400-400 220.982 0 400 178.942 400 400 0 221.060-178.862 400-400 400zM726.488 401.6c0 134.104-144.842 136.168-144.842 185.726v12.674c0 13.254-10.746 24-24 24h-91.294c-13.254 0-24-10.746-24-24v-17.318c0-71.49 54.2-100.068 95.158-123.032 35.122-19.69 56.648-33.082 56.648-59.158 0-34.492-43.998-57.386-79.568-57.386-46.378 0-67.788 21.954-97.884 59.938-8.114 10.24-22.92 12.142-33.332 4.248l-55.648-42.196c-10.214-7.744-12.502-22.132-5.288-32.726 47.254-69.388 107.442-108.37 201.15-108.37 98.142 0 202.9 76.608 202.9 177.6zM596 736c0 46.318-37.682 84-84 84s-84-37.682-84-84 37.682-84 84-84 84 37.682 84 84z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">Sita<\/div><meta itemprop=\"name\" content=\"Sita\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-2\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-00e70a1\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">Nie zachowujemy sit. Po sko\u0144czonym druku sita s\u0105 zmywane, nie ma mo\u017cliwo\u015bci przetrzymywania ich tygodniami w celu dodruk\u00f3w. W przypadku dodruku sita s\u0105 przygotowywane od pocz\u0105tku, i ponownie klient za nie p\u0142aci. Warto wzi\u0105\u0107 to pod uwag\u0119 rozwa\u017caj\u0105c ilo\u015b\u0107 koszulek \u2014 cena przygotowania sit rozbija si\u0119 na jednostkow\u0105 cen\u0119 koszulki \u2014 im wi\u0119kszy nak\u0142ad, tym taniej wychodzi na sztuce. Przygotowanie sita to proces czasoch\u0142onny, skomplikowany, sk\u0142adaj\u0105cy si\u0119 z kilku etap\u00f3w \u2014 st\u0105d wynika cena i MOQ.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-c8ea02f gsopen\" id=\"gspb_accordionitem-gsbp-c8ea02f\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-3\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-c8ea02f\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 1024 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M512 16c-273.914 0-496 222.166-496 496 0 273.994 222.086 496 496 496s496-222.006 496-496c0-273.834-222.086-496-496-496zM512 912c-221.064 0-400-178.862-400-400 0-220.99 178.944-400 400-400 220.982 0 400 178.942 400 400 0 221.060-178.862 400-400 400zM726.488 401.6c0 134.104-144.842 136.168-144.842 185.726v12.674c0 13.254-10.746 24-24 24h-91.294c-13.254 0-24-10.746-24-24v-17.318c0-71.49 54.2-100.068 95.158-123.032 35.122-19.69 56.648-33.082 56.648-59.158 0-34.492-43.998-57.386-79.568-57.386-46.378 0-67.788 21.954-97.884 59.938-8.114 10.24-22.92 12.142-33.332 4.248l-55.648-42.196c-10.214-7.744-12.502-22.132-5.288-32.726 47.254-69.388 107.442-108.37 201.15-108.37 98.142 0 202.9 76.608 202.9 177.6zM596 736c0 46.318-37.682 84-84 84s-84-37.682-84-84 37.682-84 84-84 84 37.682 84 84z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">MOQ (minimum of quantity = minimalny nak\u0142ad)<\/div><meta itemprop=\"name\" content=\"MOQ (minimum of quantity = minimalny nak\u0142ad)\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-3\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-c8ea02f\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">MOQ to 50 szt \/ wz\u00f3r. Wynika to z procesu przygotowania sit (patrz powy\u017cej).<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-30775ae gsopen\" id=\"gspb_accordionitem-gsbp-30775ae\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-4\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-30775ae\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 1024 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M512 16c-273.914 0-496 222.166-496 496 0 273.994 222.086 496 496 496s496-222.006 496-496c0-273.834-222.086-496-496-496zM512 912c-221.064 0-400-178.862-400-400 0-220.99 178.944-400 400-400 220.982 0 400 178.942 400 400 0 221.060-178.862 400-400 400zM726.488 401.6c0 134.104-144.842 136.168-144.842 185.726v12.674c0 13.254-10.746 24-24 24h-91.294c-13.254 0-24-10.746-24-24v-17.318c0-71.49 54.2-100.068 95.158-123.032 35.122-19.69 56.648-33.082 56.648-59.158 0-34.492-43.998-57.386-79.568-57.386-46.378 0-67.788 21.954-97.884 59.938-8.114 10.24-22.92 12.142-33.332 4.248l-55.648-42.196c-10.214-7.744-12.502-22.132-5.288-32.726 47.254-69.388 107.442-108.37 201.15-108.37 98.142 0 202.9 76.608 202.9 177.6zM596 736c0 46.318-37.682 84-84 84s-84-37.682-84-84 37.682-84 84-84 84 37.682 84 84z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">Proces zam\u00f3wienia<\/div><meta itemprop=\"name\" content=\"Proces zam\u00f3wienia\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-4\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-30775ae\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">&#8211; wst\u0119pne ustalenia omawiane mailowo, telefonicznie b\u0105d\u017a via social media<br>&#8211; przes\u0142anie i akceptacja plik\u00f3w<br>&#8211; akceptacja wizualizacji i ustalenie warunk\u00f3w finansowych przez klienta wy\u0142\u0105cznie w formie mailowej, na adres&nbsp;<a href=\"https:\/\/sinfinityclothing.com\/en\/%22mailto:info@sinfinityclothing.com\/%22\/\">info@sinfinityclothing.com<\/a>, co jest jednoznaczne ze z\u0142o\u017ceniem zlecenia.<br>W przypadku rezygnacji z us\u0142ugi, klient zobowi\u0105zuje si\u0119 pokry\u0107 koszty poniesione przez Sinfinity Clothing S.C., zale\u017cne od momentu procesu produkcyjnego.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-1686b65 gsopen\" id=\"gspb_accordionitem-gsbp-1686b65\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-5\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-1686b65\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 1024 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M512 16c-273.914 0-496 222.166-496 496 0 273.994 222.086 496 496 496s496-222.006 496-496c0-273.834-222.086-496-496-496zM512 912c-221.064 0-400-178.862-400-400 0-220.99 178.944-400 400-400 220.982 0 400 178.942 400 400 0 221.060-178.862 400-400 400zM726.488 401.6c0 134.104-144.842 136.168-144.842 185.726v12.674c0 13.254-10.746 24-24 24h-91.294c-13.254 0-24-10.746-24-24v-17.318c0-71.49 54.2-100.068 95.158-123.032 35.122-19.69 56.648-33.082 56.648-59.158 0-34.492-43.998-57.386-79.568-57.386-46.378 0-67.788 21.954-97.884 59.938-8.114 10.24-22.92 12.142-33.332 4.248l-55.648-42.196c-10.214-7.744-12.502-22.132-5.288-32.726 47.254-69.388 107.442-108.37 201.15-108.37 98.142 0 202.9 76.608 202.9 177.6zM596 736c0 46.318-37.682 84-84 84s-84-37.682-84-84 37.682-84 84-84 84 37.682 84 84z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">Dodruk<\/div><meta itemprop=\"name\" content=\"Dodruk\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-5\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-1686b65\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">Przy dodruku tego samego wzoru (wykluczaj\u0105c nadruki bia\u0142e i czarne) nale\u017cy liczy\u0107 si\u0119, \u017ce kolejna partia mo\u017ce nieznacznie r\u00f3\u017cni\u0107 si\u0119 kolorystycznie od poprzedniej. Wynika to ze specyfiki mieszania farb. Dok\u0142adamy oczywi\u015bcie wszelkich stara\u0144 aby kolory zgadza\u0142y si\u0119 z wizualizacj\u0105 (plikiem produkcyjnym). Je\u017celi klient \u017cyczy sobie, aby referencj\u0105 by\u0142a poprzednia wersja nadruku, musi nam j\u0105 dostarczy\u0107 (na sw\u00f3j koszt).<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-cc50939 gsopen\" id=\"gspb_accordionitem-gsbp-cc50939\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-6\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-cc50939\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 1024 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M512 16c-273.914 0-496 222.166-496 496 0 273.994 222.086 496 496 496s496-222.006 496-496c0-273.834-222.086-496-496-496zM512 912c-221.064 0-400-178.862-400-400 0-220.99 178.944-400 400-400 220.982 0 400 178.942 400 400 0 221.060-178.862 400-400 400zM726.488 401.6c0 134.104-144.842 136.168-144.842 185.726v12.674c0 13.254-10.746 24-24 24h-91.294c-13.254 0-24-10.746-24-24v-17.318c0-71.49 54.2-100.068 95.158-123.032 35.122-19.69 56.648-33.082 56.648-59.158 0-34.492-43.998-57.386-79.568-57.386-46.378 0-67.788 21.954-97.884 59.938-8.114 10.24-22.92 12.142-33.332 4.248l-55.648-42.196c-10.214-7.744-12.502-22.132-5.288-32.726 47.254-69.388 107.442-108.37 201.15-108.37 98.142 0 202.9 76.608 202.9 177.6zM596 736c0 46.318-37.682 84-84 84s-84-37.682-84-84 37.682-84 84-84 84 37.682 84 84z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">Zalecenia<\/div><meta itemprop=\"name\" content=\"Zalecenia\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-6\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-cc50939\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">Producenci koszulek zalecaj\u0105 pra\u0107 w 30\u00b0C i nie u\u017cywa\u0107 suszarek b\u0119bnowych.<br>Producenci farb zalecaj\u0105 pra\u0107 na lewej stronie i nie prasowa\u0107.<br>Producenci chemii wywabowej zalecaj\u0105 upra\u0107 koszulk\u0119 przed pierwszym u\u017cyciem.<br>Koszulki wykonane ze 100% bawe\u0142ny mog\u0105 si\u0119 skurczy\u0107 w pierwszym praniu 3\u20135%. Jest to normalny proces w przypadku tego surowca.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-0bf4ece gsopen\" id=\"gspb_accordionitem-gsbp-0bf4ece\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-7\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-0bf4ece\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 1024 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M512 16c-273.914 0-496 222.166-496 496 0 273.994 222.086 496 496 496s496-222.006 496-496c0-273.834-222.086-496-496-496zM512 912c-221.064 0-400-178.862-400-400 0-220.99 178.944-400 400-400 220.982 0 400 178.942 400 400 0 221.060-178.862 400-400 400zM726.488 401.6c0 134.104-144.842 136.168-144.842 185.726v12.674c0 13.254-10.746 24-24 24h-91.294c-13.254 0-24-10.746-24-24v-17.318c0-71.49 54.2-100.068 95.158-123.032 35.122-19.69 56.648-33.082 56.648-59.158 0-34.492-43.998-57.386-79.568-57.386-46.378 0-67.788 21.954-97.884 59.938-8.114 10.24-22.92 12.142-33.332 4.248l-55.648-42.196c-10.214-7.744-12.502-22.132-5.288-32.726 47.254-69.388 107.442-108.37 201.15-108.37 98.142 0 202.9 76.608 202.9 177.6zM596 736c0 46.318-37.682 84-84 84s-84-37.682-84-84 37.682-84 84-84 84 37.682 84 84z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">Reklamacje<\/div><meta itemprop=\"name\" content=\"Reklamacje\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-7\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-0bf4ece\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">Reklamacje przyjmujemy tylko i wy\u0142\u0105cznie, je\u017celi nadruk jest technicznie \u017ale wykonany (spiera si\u0119), b\u0105d\u017a nast\u0105pi\u0142a ra\u017c\u0105ca r\u00f3\u017cnica mi\u0119dzy mockupem a projektem.<br>Nie ma mo\u017cliwo\u015bci zwrotu towaru po wydrukowaniu, jedyn\u0105 mo\u017cliwo\u015bci\u0105 za\u0142atwienia reklamacji jest ponowny wydruk zlecenia.<br>Ka\u017cd\u0105 reklamacj\u0119 rozpatrujemy indywidualnie i zawsze staramy si\u0119 doj\u015b\u0107 do porozumienia tak, by klient by\u0142 zadowolony.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-accordionitem gs-accordion-item gspb_accordionitem-gsbp-6316116 gsopen\" id=\"gspb_accordionitem-gsbp-6316116\" itemscope itemprop=\"mainEntity\" itemtype=\"https:\/\/schema.org\/Question\"><div id=\"gs-trigger-gsbp-eaac55e-8\" class=\"gs-accordion-item__title\" aria-expanded=\"true\" role=\"button\" tabindex=\"0\" aria-controls=\"gspb-accordion-item-content-gsbp-6316116\"><span class=\"icontitle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 1024 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M512 16c-273.914 0-496 222.166-496 496 0 273.994 222.086 496 496 496s496-222.006 496-496c0-273.834-222.086-496-496-496zM512 912c-221.064 0-400-178.862-400-400 0-220.99 178.944-400 400-400 220.982 0 400 178.942 400 400 0 221.060-178.862 400-400 400zM726.488 401.6c0 134.104-144.842 136.168-144.842 185.726v12.674c0 13.254-10.746 24-24 24h-91.294c-13.254 0-24-10.746-24-24v-17.318c0-71.49 54.2-100.068 95.158-123.032 35.122-19.69 56.648-33.082 56.648-59.158 0-34.492-43.998-57.386-79.568-57.386-46.378 0-67.788 21.954-97.884 59.938-8.114 10.24-22.92 12.142-33.332 4.248l-55.648-42.196c-10.214-7.744-12.502-22.132-5.288-32.726 47.254-69.388 107.442-108.37 201.15-108.37 98.142 0 202.9 76.608 202.9 177.6zM596 736c0 46.318-37.682 84-84 84s-84-37.682-84-84 37.682-84 84-84 84 37.682 84 84z\"><\/path><\/svg><\/span><div class=\"gs-accordion-item__heading\">Inne<\/div><meta itemprop=\"name\" content=\"Inne\"\/><span class=\"iconfortoggle\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 384 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M375.6 529l-293.6 296c-9.4 9.4-24.6 9.4-34 0l-39.6-39.6c-9.4-9.4-9.4-24.6 0-34l237-239.4-237-239.4c-9.4-9.4-9.4-24.6 0-34l39.6-39.6c9.4-9.4 24.6-9.4 34 0l293.6 296c9.4 9.4 9.4 24.6 0 34z\"><\/path><\/svg><\/span><\/div><div aria-labelledby=\"gs-trigger-gsbp-eaac55e-8\" class=\"gs-accordion-item__content\" itemscope itemprop=\"acceptedAnswer\" itemtype=\"https:\/\/schema.org\/Answer\" id=\"gspb-accordion-item-content-gsbp-6316116\" aria-hidden=\"false\"><div class=\"gs-accordion-item__text\" itemprop=\"text\">\n<p class=\"wp-block-paragraph\">Je\u017celi masz inne pytania, b\u0105d\u017a co\u015b budzi Twoje w\u0105tpliwo\u015bci \u2014 zapraszamy do kontaktu telefonicznego lub mailowego.<\/p>\n<\/div><\/div><\/div>\n<\/div>\n\n\n\n<div style=\"height:24px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group is-content-justification-left is-nowrap is-layout-flex wp-container-core-group-is-layout-916f677d wp-block-group-is-layout-flex\" style=\"padding-top:var(--wp--preset--spacing--50)\"><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-container gspb_container gspb_container-gsbp-e560694\" id=\"gspb_container-id-gsbp-e560694\">\n<div class=\"wp-block-greenshift-blocks-button gspb_button_wrapper gspb_button-id-gsbp-cd10e03c-3a7c\" id=\"gspb_button-id-gsbp-cd10e03c-3a7c\"><a class=\"gspb-buttonbox\" href=\"https:\/\/sinfinityclothing.com\/en\/?page_id=46\" rel=\"noopener\"><span class=\"gspb-buttonbox-textwrap\"><span class=\"gspb-buttonbox-text\"><span class=\"gspb-buttonbox-title\">Contact<\/span><\/span><\/span><\/a><\/div>\n\n\n\n<div class=\"wp-block-greenshift-blocks-button gspb_button_wrapper gspb_button-id-gsbp-f90fd34\" id=\"gspb_button-id-gsbp-f90fd34\"><a class=\"gspb-buttonbox\" rel=\"noopener\"><span class=\"gspb-buttonbox-textwrap\"><span class=\"gspb-buttonbox-text\"><span class=\"gspb-buttonbox-title\">Get a quote<\/span><\/span><span class=\"gspb-buttonbox-icon\"><svg class=\"\" style=\"display:inline-block;vertical-align:middle\" width=\"15\" height=\"15\" viewbox=\"0 0 512 1024\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path style=\"fill:#565D66\" d=\"M49.414 76.202l-39.598 39.596c-9.372 9.372-9.372 24.568 0 33.942l361.398 362.26-361.398 362.26c-9.372 9.372-9.372 24.568 0 33.942l39.598 39.598c9.372 9.372 24.568 9.372 33.942 0l418.828-418.828c9.372-9.372 9.372-24.568 0-33.942l-418.828-418.828c-9.374-9.374-24.57-9.374-33.942 0z\"><\/path><\/svg><\/span><\/span><\/a><\/div>\n<\/div>\n<\/div>\n <\/div><\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_gspb_post_css":"#gspb_row-id-gsbp-86f7b08,#gspb_row-id-gsbp-fc3aee0{justify-content:space-between;margin-top:0;margin-bottom:0;display:flex;flex-wrap:wrap}#gspb_row-id-gsbp-fc3aee0>.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap;max-width:1200px}div[id^=gspb_col-id]{box-sizing:border-box;position:relative;padding:var(--gs-row-column-padding, 15px min(3vw, 20px))}#gspb_col-id-gsbp-573af12.gspb_row__col--12{width:100%}@media (max-width:575.98px){#gspb_col-id-gsbp-573af12.gspb_row__col--12{width:100%}}body #gspb_col-id-gsbp-573af12.gspb_row__col--12,body #gspb_col-id-gsbp-96a103f.gspb_row__col--12{display:flex;flex-direction:column;align-items:center}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item.gsclose>.gs-accordion-item__content{overflow:hidden;opacity:0}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item.gsopen>.gs-accordion-item__content{opacity:1;max-height:5000px}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__title>.gs-accordion-item__heading{outline:0;text-decoration:none;margin:0!important;padding:0!important;flex-grow:1}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__title{z-index:1;margin:0;cursor:pointer;transition:all .3s ease-in-out;position:relative;display:flex;justify-content:space-between;align-items:center;flex-wrap:nowrap}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__content{z-index:0;position:relative;max-height:0;will-change:max-height;transition:all .25s ease-out}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__content,#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__title{background-color:#ffffff21;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;border-style:solid;border-width:1px;border-color:#ffffff36;color:#fff}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item__title>*{color:#fff}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__content{background-color:#ffffff1f;border-color:#00000000 #ffffff2b #ffffff2b;color:#e0e0e0}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__content .wp-block a,#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__content a{color:var(--gs-colorcolor6, #ffffff)}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__content .wp-block a:hover,#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__content a:hover{color:var(--gs-colorcolor2, #ffc908)}#gspb_accordion-id-gsbp-eaac55e span.iconfortoggle .gs-iconafter,#gspb_accordion-id-gsbp-eaac55e span.iconfortoggle .gs-iconbefore{background-color:#fff}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__title span.iconfortoggle{margin-left:15px}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item{margin-bottom:1em}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__content>.gs-accordion-item__text,#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item>.gs-accordion-item__title{padding:15px 20px}#gspb_accordion-id-gsbp-eaac55e span.iconfortoggle svg{height:16px!important;width:16px!important;min-width:16px!important;fill:currentColor!important;margin:0!important}#gspb_accordion-id-gsbp-eaac55e span.iconfortoggle svg path,#gspb_accordion-id-gsbp-eaac55e span.iconfortoggle svg:hover,#gspb_accordion-id-gsbp-eaac55e span.iconfortoggle svg:hover path{fill:currentColor!important}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item__title span.iconfortoggle{transition:transform .3s ease-in-out;display:inline-flex}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item__title span.iconfortoggle>*{vertical-align:top!important}#gspb_accordion-id-gsbp-eaac55e .gs-accordion-item.gsopen span.iconfortoggle{transform:rotate(90deg)}#gspb_accordionitem-gsbp-ba9b996 span.icontitle svg{height:16px!important;width:16px!important;min-width:16px!important;fill:var(--gs-colorcolor2, #ffc908)!important;margin:0!important}#gspb_accordionitem-gsbp-ba9b996 span.icontitle svg path{fill:var(--gs-colorcolor2, #ffc908)!important}#gspb_accordionitem-gsbp-ba9b996 span.icontitle{display:inline-flex;align-items:center;justify-content:center;margin-right:1em}#gspb_accordionitem-gsbp-00e70a1 span.icontitle svg,#gspb_accordionitem-gsbp-be6771d span.icontitle svg{height:16px!important;width:16px!important;min-width:16px!important;fill:var(--gs-colorcolor2, #ffc908)!important;margin:0!important}#gspb_accordionitem-gsbp-00e70a1 span.icontitle svg path,#gspb_accordionitem-gsbp-be6771d span.icontitle svg path{fill:var(--gs-colorcolor2, #ffc908)!important}#gspb_accordionitem-gsbp-00e70a1 span.icontitle,#gspb_accordionitem-gsbp-be6771d span.icontitle{display:inline-flex;align-items:center;justify-content:center;margin-right:1em}#gspb_accordionitem-gsbp-30775ae span.icontitle svg,#gspb_accordionitem-gsbp-c8ea02f span.icontitle svg{height:16px!important;width:16px!important;min-width:16px!important;fill:var(--gs-colorcolor2, #ffc908)!important;margin:0!important}#gspb_accordionitem-gsbp-30775ae span.icontitle svg path,#gspb_accordionitem-gsbp-c8ea02f span.icontitle svg path{fill:var(--gs-colorcolor2, #ffc908)!important}#gspb_accordionitem-gsbp-30775ae span.icontitle,#gspb_accordionitem-gsbp-c8ea02f span.icontitle{display:inline-flex;align-items:center;justify-content:center;margin-right:1em}#gspb_accordionitem-gsbp-1686b65 span.icontitle svg,#gspb_accordionitem-gsbp-cc50939 span.icontitle svg{height:16px!important;width:16px!important;min-width:16px!important;fill:var(--gs-colorcolor2, #ffc908)!important;margin:0!important}#gspb_accordionitem-gsbp-1686b65 span.icontitle svg path,#gspb_accordionitem-gsbp-cc50939 span.icontitle svg path{fill:var(--gs-colorcolor2, #ffc908)!important}#gspb_accordionitem-gsbp-1686b65 span.icontitle,#gspb_accordionitem-gsbp-cc50939 span.icontitle{display:inline-flex;align-items:center;justify-content:center;margin-right:1em}#gspb_accordionitem-gsbp-0bf4ece span.icontitle svg,#gspb_accordionitem-gsbp-6316116 span.icontitle svg{height:16px!important;width:16px!important;min-width:16px!important;fill:var(--gs-colorcolor2, #ffc908)!important;margin:0!important}#gspb_accordionitem-gsbp-0bf4ece span.icontitle svg path,#gspb_accordionitem-gsbp-6316116 span.icontitle svg path{fill:var(--gs-colorcolor2, #ffc908)!important}#gspb_accordionitem-gsbp-0bf4ece span.icontitle,#gspb_accordionitem-gsbp-6316116 span.icontitle{display:inline-flex;align-items:center;justify-content:center;margin-right:1em}.gspb_container-id-gsbp-e560694{flex-direction:column;box-sizing:border-box}#gspb_container-id-gsbp-51c4d8a.gspb_container>p:last-of-type,#gspb_container-id-gsbp-e560694.gspb_container>p:last-of-type{margin-bottom:0}#gspb_container-id-gsbp-e560694.gspb_container{position:relative;display:flex}@media (max-width:575.98px){#gspb_container-id-gsbp-e560694.gspb_container{flex-direction:column;row-gap:1em;column-gap:1em}}.gspb_button-id-gsbp-cd10e03c-3a7c,.gspb_button-id-gsbp-f90fd34{display:flex;justify-content:flex-start}.gspb_button-id-gsbp-cd10e03c-3a7c .gspb-buttonbox-text{display:flex;flex-direction:column}.gspb_button-id-gsbp-cd10e03c-3a7c>.gspb-buttonbox{display:var(--display, inline-flex);text-align:center;font-family:var(--theme-button-font-family, var(--theme-font-family));font-size:var(--theme-button-font-style);font-weight:var(--theme-button-font-weight);font-style:var(--theme-button-font-size);line-height:var(--theme-button-line-height);letter-spacing:var(--theme-button-letter-spacing);text-transform:var(--theme-button-text-transform);-webkit-text-decoration:var(--theme-button-text-decoration);text-decoration:var(--theme-button-text-decoration);color:var(--theme-button-text-initial-color);border:var(--button-border);background-color:var(--theme-button-background-initial-color);min-height:var(--theme-button-min-height);appearance:none;user-select:none;border-radius:var(--theme-button-border-radius, 3px);--has-link-decoration:var(--false);padding:var(--theme-button-padding);align-items:center;justify-content:center;position:relative;z-index:0;cursor:pointer;box-sizing:border-box;margin-top:0;padding:16px 32px 14px;background-color:var(--gs-colorcolor2, #ffc908);font-size:16px;color:var(--gs-colorcolor4, #2a2a2a);transition:all .2s cubic-bezier(.42,0,.58,1)}.gspb_button-id-gsbp-cd10e03c-3a7c>.gspb-buttonbox:hover{border-color:var(--theme-button-border-hover-color);color:var(--theme-button-text-hover-color);background-color:var(--theme-button-background-hover-color);background-color:var(--gs-colorcolor2, #ffc908)!important;color:var(--gs-colorcolor4, #2a2a2a)}.gspb_button-id-gsbp-cd10e03c-3a7c>.gspb-buttonbox,.gspb_button-id-gsbp-cd10e03c-3a7c>.gspb-buttonbox>.gspb_backgroundOverlay{border-top-left-radius:99px;border-top-right-radius:99px;border-bottom-right-radius:99px;border-bottom-left-radius:99px}.gspb_button-id-gsbp-cd10e03c-3a7c>.gspb-buttonbox .gspb-buttonbox-icon svg,.gspb_button-id-gsbp-cd10e03c-3a7c>.gspb-buttonbox .gspb-buttonbox-icon svg path{transition:all .2s cubic-bezier(.42,0,.58,1)}.gspb_button-id-gsbp-cd10e03c-3a7c>.gspb-buttonbox:hover{transform:scale(1.03)}.gspb_button-id-gsbp-f90fd34 .gspb-buttonbox-text{display:flex;flex-direction:column}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox{display:var(--display, inline-flex);text-align:center;font-family:var(--theme-button-font-family, var(--theme-font-family));font-size:var(--theme-button-font-style);font-weight:var(--theme-button-font-weight);font-style:var(--theme-button-font-size);line-height:var(--theme-button-line-height);letter-spacing:var(--theme-button-letter-spacing);text-transform:var(--theme-button-text-transform);-webkit-text-decoration:var(--theme-button-text-decoration);text-decoration:var(--theme-button-text-decoration);color:var(--theme-button-text-initial-color);border:var(--button-border);background-color:var(--theme-button-background-initial-color);min-height:var(--theme-button-min-height);appearance:none;user-select:none;border-radius:var(--theme-button-border-radius, 3px);--has-link-decoration:var(--false);padding:var(--theme-button-padding);align-items:center;justify-content:center;position:relative;z-index:0;cursor:pointer;box-sizing:border-box}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox:hover{border-color:var(--theme-button-border-hover-color);color:var(--theme-button-text-hover-color);background-color:var(--theme-button-background-hover-color)}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox>.gspb-buttonbox-textwrap>.gspb-buttonbox-icon{display:flex}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox .gspb-buttonbox-icon svg,.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox .gspb-buttonbox-icon svg path{fill:currentColor!important}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox .gspb-buttonbox-icon svg{margin:0!important}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox>.gspb-buttonbox-textwrap{display:flex;flex-direction:row;align-items:center}.gspb_button-id-gsbp-f90fd34 .gspb-buttonbox-icon{margin-left:13px}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox .gspb-buttonbox-icon{transition:all .5s cubic-bezier(.42,0,.58,1)}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox:hover .gspb-buttonbox-icon{transform:translateX(12px)}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox{margin-top:0;padding:16px 32px 14px;background-color:#00000000;font-size:16px;color:#fff}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox:hover{background-color:var(--gs-colorcolor2, #ffc908)!important;color:var(--gs-colorcolor4, #2a2a2a)}.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox,.gspb_button-id-gsbp-f90fd34>.gspb-buttonbox>.gspb_backgroundOverlay{border-top-left-radius:99px;border-top-right-radius:99px;border-bottom-right-radius:99px;border-bottom-left-radius:99px}#gspb_row-id-gsbp-86f7b08>.gspb_row__content{display:flex;justify-content:space-between;margin:0 auto;width:100%;flex-wrap:wrap;max-width:1200px}.gspb_row{position:relative}#gspb_row-id-gsbp-86f7b08 .gspb_shape-divider-container--top svg .gspb_st1,#gspb_row-id-gsbp-86f7b08 .gspb_shape-divider-container--top svg .gspb_st2{opacity:.5}#gspb_row-id-gsbp-86f7b08 .gspb_shape-divider-container--top svg .gspb_st0{opacity:1}#gspb_row-id-gsbp-86f7b08 .gspb_shape-divider-container--top{top:-43px;z-index:1}#gspb_row-id-gsbp-86f7b08 .gspb_shape-divider-container--top svg{height:45px}#gspb_row-id-gsbp-86f7b08{padding-top:10vh;padding-bottom:10vh;background-color:#000;background-size:contain;background-position:50% 50%}@media (max-width:575.98px){#gspb_row-id-gsbp-86f7b08{background-size:cover}}#gspb_row-id-gsbp-86f7b08{background-image:url(https:\/\/sinfinityclothing.com\/wp-content\/uploads\/2025\/10\/proces.png)}#gspb_row-id-gsbp-86f7b08:hover{background-size:contain}@media (max-width:575.98px){#gspb_row-id-gsbp-86f7b08:hover{background-size:cover}}#gspb_col-id-gsbp-96a103f.gspb_row__col--12{width:100%}@media (max-width:575.98px){#gspb_col-id-gsbp-96a103f.gspb_row__col--12{width:100%}}.gspb_container-id-gsbp-51c4d8a{flex-direction:column;box-sizing:border-box}#gspb_container-id-gsbp-51c4d8a.gspb_container,#gspb_container-id-gsbp-51c4d8a.gspb_container>.gspb_backgroundOverlay{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px}#gspb_container-id-gsbp-51c4d8a.gspb_container{position:relative;display:flex;flex-direction:row;justify-content:flex-start;align-items:center;column-gap:.4rem;box-shadow:0 2px 4px 0 rgba(0,0,0,.07);margin-bottom:0;padding:.3rem .7rem;border-style:solid;border-width:1px;border-color:#585858;isolation:isolate}#gspb_container-id-gsbp-51c4d8a.gspb_container>.gspb_backgroundOverlay{position:absolute;top:0;left:0;width:100%;height:100%;z-index:-1;-webkit-backdrop-filter:blur(1.8px);backdrop-filter:blur(1.8px);background-color:#ffffff00}#gspb_iconBox-id-gsbp-8d3d130 svg{width:72px;height:1rem!important;width:1rem!important;min-width:1rem!important;fill:#9c9c9c!important;margin:0!important}#gspb_iconBox-id-gsbp-8d3d130{justify-content:center;display:flex}#gspb_iconBox-id-gsbp-8d3d130 svg path{fill:#9c9c9c!important}#gspb_iconBox-id-gsbp-8d3d130 .gspb_iconBox__wrapper{margin:0!important;padding:0}.gspb_text-id-gsbp-5360b17{font-size:14px;font-weight:600!important;color:#bbb;margin-top:0!important}#gspb_heading-id-gsbp-22ade7e{font-size:clamp(2.2rem,4vw,2.8rem);line-height:clamp(2.75rem,4.7vw,3.5rem);text-align:left!important;color:var(--gs-colorcolor6, #ffffff);margin-top:12px;margin-bottom:24px}#gspb_heading-id-gsbp-22ade7e .gsap-g-line{text-align:left!important}","footnotes":""},"class_list":["post-44","page","type-page","status-publish","hentry"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/sinfinityclothing.com\/en\/wp-json\/wp\/v2\/pages\/44","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sinfinityclothing.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sinfinityclothing.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sinfinityclothing.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sinfinityclothing.com\/en\/wp-json\/wp\/v2\/comments?post=44"}],"version-history":[{"count":13,"href":"https:\/\/sinfinityclothing.com\/en\/wp-json\/wp\/v2\/pages\/44\/revisions"}],"predecessor-version":[{"id":671,"href":"https:\/\/sinfinityclothing.com\/en\/wp-json\/wp\/v2\/pages\/44\/revisions\/671"}],"wp:attachment":[{"href":"https:\/\/sinfinityclothing.com\/en\/wp-json\/wp\/v2\/media?parent=44"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}